{"id":13953,"count":2,"description":"","link":"https:\/\/seamheads.com\/blog\/tag\/wee-hours\/","name":"Wee Hours","slug":"wee-hours","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/13953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/posts?tags=13953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}