{"id":20887,"count":1,"description":"","link":"https:\/\/seamheads.com\/blog\/tag\/ecu-pirates\/","name":"Ecu Pirates","slug":"ecu-pirates","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"ZC2u-xAzmBB3LwWFMVKHIDadqgqy8zeJuFAhAC_F2e8\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/seamheads.com\/blog\/tag\/ecu-pirates\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/20887\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seamheads.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/tag\\\/ecu-pirates\\\/#listItem\",\"name\":\"Ecu Pirates\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/tag\\\/ecu-pirates\\\/#listItem\",\"position\":2,\"name\":\"Ecu Pirates\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/20887\\\/#collectionpage\",\"url\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/20887\\\/\",\"name\":\"Ecu Pirates | Seamheads.com\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/20887\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/#organization\",\"name\":\"Seamheads.com\",\"description\":\"Celebrating baseball history one pitch at a time\",\"url\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/\",\"telephone\":\"+15038886604\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-content\\\/uploads\\\/Seamheads-2018-Header-1.png\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/20887\\\/#organizationLogo\",\"width\":613,\"height\":95,\"caption\":\"Seamheads Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/20887\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seamheads\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/\",\"name\":\"Seamheads.com\",\"description\":\"Celebrating baseball history one pitch at a time\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/seamheads.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ecu Pirates | Seamheads.com","description":"","canonical_url":"https:\/\/seamheads.com\/blog\/tag\/ecu-pirates\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"ZC2u-xAzmBB3LwWFMVKHIDadqgqy8zeJuFAhAC_F2e8","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/seamheads.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/seamheads.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/seamheads.com\/blog\/tag\/ecu-pirates\/#listItem","name":"Ecu Pirates"}},{"@type":"ListItem","@id":"https:\/\/seamheads.com\/blog\/tag\/ecu-pirates\/#listItem","position":2,"name":"Ecu Pirates","previousItem":{"@type":"ListItem","@id":"https:\/\/seamheads.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887\/#collectionpage","url":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887\/","name":"Ecu Pirates | Seamheads.com","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/seamheads.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/seamheads.com\/blog\/#organization","name":"Seamheads.com","description":"Celebrating baseball history one pitch at a time","url":"https:\/\/seamheads.com\/blog\/","telephone":"+15038886604","logo":{"@type":"ImageObject","url":"https:\/\/seamheads.com\/blog\/wp-content\/uploads\/Seamheads-2018-Header-1.png","@id":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887\/#organizationLogo","width":613,"height":95,"caption":"Seamheads Logo"},"image":{"@id":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/seamheads"]},{"@type":"WebSite","@id":"https:\/\/seamheads.com\/blog\/#website","url":"https:\/\/seamheads.com\/blog\/","name":"Seamheads.com","description":"Celebrating baseball history one pitch at a time","inLanguage":"en-US","publisher":{"@id":"https:\/\/seamheads.com\/blog\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/20887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/posts?tags=20887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}