{"id":5474,"count":1,"description":"","link":"https:\/\/seamheads.com\/blog\/tag\/bob-dernier\/","name":"Bob Dernier","slug":"bob-dernier","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags\/5474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/seamheads.com\/blog\/wp-json\/wp\/v2\/posts?tags=5474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}